{"id":70277,"date":"2023-12-01T09:54:32","date_gmt":"2023-12-01T08:54:32","guid":{"rendered":"https:\/\/fsmcv.org\/certamens\/52e-certamen-provincial-de-bandes-de-musica-de-la-provincia-dalacant\/"},"modified":"2023-12-01T10:01:19","modified_gmt":"2023-12-01T09:01:19","slug":"52e-certamen-provincial-de-bandes-de-musica-de-la-provincia-dalacant","status":"publish","type":"post","link":"https:\/\/fsmcv.org\/vl\/societats-musicals\/52e-certamen-provincial-de-bandes-de-musica-de-la-provincia-dalacant\/","title":{"rendered":"52\u00e9 CERTAMEN PROVINCIAL DE BANDES DE M\u00daSICA DE LA PROV\u00cdNCIA D&#8217;ALACANT"},"content":{"rendered":"\n<p>Amb la finalitat de fomentar la interpretaci\u00f3 musical i la difusi\u00f3 cultural, la Diputaci\u00f3 d&#8217;Alacant fa p\u00fablica la Convocat\u00f2ria i les bases de la 52\u00e9 edici\u00f3 del Certamen Provincial de Bandes de M\u00fasica dependents de Societats Musicals Federades de la prov\u00edncia d&#8217;Alacant.<\/p>\n\n<p>Comptar\u00e0 amb quatre modalitats, on les societats guanyadores rebran des de 2.800\u20ac fins a 4.800\u20ac depenent de la secci\u00f3.<\/p>\n\n<p>El termini d&#8217;inscripci\u00f3 ser\u00e0 de DEU DIES NATURALS a partir de l&#8217;endem\u00e0 de la publicaci\u00f3 de l&#8217;EXTRACTE d&#8217;esta Convocat\u00f2ria en el Butllet\u00ed Oficial de la Prov\u00edncia d&#8217;Alacant. <\/p>\n\n<p>Adjuntem bases:<\/p>\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/fsmcv.org\/wp-content\/uploads\/2023\/12\/BOP-A-Bases-Certamen-Alicante.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of BOP-A-Bases-52-Certamen-Alicante.\"><\/object><a id=\"wp-block-file--media-5d39d980-1ac1-4f72-a013-84912512d88c\" href=\"https:\/\/fsmcv.org\/wp-content\/uploads\/2023\/12\/BOP-A-Bases-Certamen-Alicante.pdf\">BOP-A-Bases-52-Certamen-Alacant<\/a><a href=\"https:\/\/fsmcv.org\/wp-content\/uploads\/2023\/12\/BOP-A-Bases-Certamen-Alicante.pdf\" class=\"wp-block-file__button wp-element-button\" download=\"\" aria-describedby=\"wp-block-file--media-5d39d980-1ac1-4f72-a013-84912512d88c\">Desc\u00e0rrega<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Amb la finalitat de fomentar la interpretaci\u00f3 musical i la difusi\u00f3 cultural, la Diputaci\u00f3 d&#8217;Alacant fa p\u00fablica la Convocat\u00f2ria i les bases de la 52\u00e9 edici\u00f3 del Certamen Provincial de Bandes de M\u00fasica dependents de Societats Musicals Federades de la prov\u00edncia d&#8217;Alacant. Comptar\u00e0 amb quatre modalitats, on les societats guanyadores rebran des de 2.800\u20ac fins [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":59514,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-70277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societats-musicals"],"_links":{"self":[{"href":"https:\/\/fsmcv.org\/vl\/wp-json\/wp\/v2\/posts\/70277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fsmcv.org\/vl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fsmcv.org\/vl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fsmcv.org\/vl\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/fsmcv.org\/vl\/wp-json\/wp\/v2\/comments?post=70277"}],"version-history":[{"count":0,"href":"https:\/\/fsmcv.org\/vl\/wp-json\/wp\/v2\/posts\/70277\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fsmcv.org\/vl\/wp-json\/wp\/v2\/media\/59514"}],"wp:attachment":[{"href":"https:\/\/fsmcv.org\/vl\/wp-json\/wp\/v2\/media?parent=70277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fsmcv.org\/vl\/wp-json\/wp\/v2\/categories?post=70277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fsmcv.org\/vl\/wp-json\/wp\/v2\/tags?post=70277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}